{"id":658,"date":"2017-10-18T11:38:09","date_gmt":"2017-10-18T11:38:09","guid":{"rendered":"http:\/\/lechariotelevateur.fr\/site\/?post_type=product&#038;p=658"},"modified":"2018-11-09T15:05:43","modified_gmt":"2018-11-09T15:05:43","slug":"cartouche-demineralisation-eau","status":"publish","type":"product","link":"https:\/\/lechariotelevateur.fr\/site\/nos-machines\/pieces-detachees\/equipement-atelier-magasin\/equipements-atelier-outils\/accessoires-materiels-manutention\/cartouche-demineralisation-eau\/","title":{"rendered":"CARTOUCHE D\u00c9MIN\u00c9RALISATION EAU"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>CARTOUCHE\u00a0DE D\u00c9MIN\u00c9RALISATION 2400 l<\/p>\n<p><strong><br \/>\n<\/strong>R\u00e9f. 000164<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"rsdb_etoiles alignnone size-full wp-image-133\" src=\"https:\/\/lechariotelevateur.fr\/site\/wp-content\/uploads\/2017\/04\/etoiles-etat-5-5.png\" alt=\"\" width=\"117\" height=\"20\" \/><\/p>\n","protected":false},"featured_media":659,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[11,69,89,81,80],"product_tag":[],"class_list":{"0":"post-658","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessoires-materiels-manutention","7":"product_cat-equipement-atelier-magasin","8":"product_cat-equipement-accessoires-electriques","9":"product_cat-equipements-atelier-outils","10":"product_cat-equipements-magasin","11":"pa_capacite-cap-1-a-2","12":"pa_energie-electrique","13":"pa_hauteur-de-levee-levee-0-a-1","14":"pa_neuf-occasion-neuf","15":"pa_pneus-pneus-bandage","17":"first","18":"instock","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/lechariotelevateur.fr\/site\/wp-json\/wp\/v2\/product\/658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lechariotelevateur.fr\/site\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lechariotelevateur.fr\/site\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lechariotelevateur.fr\/site\/wp-json\/wp\/v2\/comments?post=658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lechariotelevateur.fr\/site\/wp-json\/wp\/v2\/media\/659"}],"wp:attachment":[{"href":"https:\/\/lechariotelevateur.fr\/site\/wp-json\/wp\/v2\/media?parent=658"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lechariotelevateur.fr\/site\/wp-json\/wp\/v2\/product_brand?post=658"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lechariotelevateur.fr\/site\/wp-json\/wp\/v2\/product_cat?post=658"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lechariotelevateur.fr\/site\/wp-json\/wp\/v2\/product_tag?post=658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}